{"id":25547339,"date":"2025-12-10T15:10:56","date_gmt":"2025-12-10T15:10:56","guid":{"rendered":"https:\/\/orbisk.com\/blog\/alles-wissenswerte-ueber-die-iso-20001-standards-fuer-lebensmittelabfaelle\/"},"modified":"2026-01-30T12:48:22","modified_gmt":"2026-01-30T12:48:22","slug":"alles-wissenswerte-ueber-die-iso-20001-standards-fuer-lebensmittelabfaelle","status":"publish","type":"post","link":"https:\/\/orbisk.com\/de\/blog\/alles-wissenswerte-ueber-die-iso-20001-standards-fuer-lebensmittelabfaelle\/","title":{"rendered":"Alles Wissenswerte \u00fcber die ISO 20001-Standards f\u00fcr Lebensmittelabf\u00e4lle"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><p>Lebensmittelverschwendung ist l\u00e4ngst kein reines Nachhaltigkeitsthema mehr, sondern wird zunehmend zu einer regulierten gesch\u00e4ftlichen Priorit\u00e4t. W\u00e4hrend Regierungen Ziele vorgeben und Hersteller unter Druck stehen, nachweisbare Fortschritte zu zeigen, suchen Unternehmen nach einer einheitlichen Methode, um ihre Leistung im Bereich Lebensmittelabf\u00e4lle zu messen und zu steuern.<\/p><\/p>\n\n<p class=\"wp-block-paragraph\">Hier kommt ISO 20001 ins Spiel. Diese kommende Norm bietet der Lebensmittelbranche erstmals einen weltweiten, zertifizierbaren Rahmen zur Vermeidung und Reduzierung von Lebensmittelverlusten und -abf\u00e4llen entlang der gesamten Lieferkette.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-what-is-iso-20001-and-how-does-it-relate-to-your-kitchen-operations\">Was ist ISO 20001 \u2013 und was bedeutet die Norm f\u00fcr Ihre K\u00fcchenabl\u00e4ufe?<\/h2>\n\n<p class=\"wp-block-paragraph\">ISO 20001 ist eine neue Managementsystem-Norm, die sich gezielt auf die Reduzierung von Lebensmittelabf\u00e4llen entlang der gesamten Wertsch\u00f6pfungskette konzentriert. Die Einf\u00fchrung wird f\u00fcr Ende 2026 oder Anfang 2027 erwartet.<\/p>\n\n<p class=\"wp-block-paragraph\">Im Kern bietet die Norm eine klare Struktur: verstehen, wo Abf\u00e4lle entstehen, Reduktionsziele setzen, Fortschritte messen und Ergebnisse nachvollziehbar melden. Dies ist ein wiederholbarer Prozess, der sich kontinuierlich verbessert.<\/p>\n\n<p class=\"wp-block-paragraph\">ISO 20001 unterscheidet sich von freiwilligen Leitlinien, indem eine  Zertifizierbarkeit vorliegt. Sobald die Norm gilt, k\u00f6nnen unabh\u00e4ngige Pr\u00fcfer best\u00e4tigen, dass Ihr System die Anforderungen erf\u00fcllt. Das bietet Ihrem Unternehmen einen greifbaren Nachweis, der f\u00fcr Investoren, Unternehmenskunden oder Nachhaltigkeitsteams interessant ist, die statt blo\u00dfer Absichtserkl\u00e4rungen Belege f\u00fcr Fortschritte erwarten.<\/p>\n\n<p class=\"wp-block-paragraph\"><p>In den USA beeinflussen Vorschriften bereits heute die Gesch\u00e4ftspraxis: Kalifornien verlangt per <a href=\"https:\/\/calrecycle.ca.gov\/organics\/slcp\/\" target=\"_blank\" rel=\"noopener\">SB 1383<\/a> eine 75%-ige Reduzierung organischer Abf\u00e4lle und die verpflichtende Weitergabe \u00fcbersch\u00fcssiger Lebensmittel. New York schreibt <a href=\"https:\/\/www.nyc.gov\/site\/dsny\/businesses\/materials-handling\/commercial-organics-requirements.page#\" target=\"_blank\" rel=\"noopener\">die Trennung organischer Abf\u00e4lle<\/a> f\u00fcr gr\u00f6\u00dfere Betriebe vor, und <a href=\"https:\/\/www.mass.gov\/guides\/commercial-food-material-disposal-ban\" target=\"_blank\" rel=\"noopener\">Massachusetts untersagt die Entsorgung organischer Abf\u00e4lle<\/a> f\u00fcr Betriebe mit mehr als einer halben Tonne pro Woche. Gleichzeitig erfasst die <a href=\"https:\/\/www.epa.gov\/land-research\/quantifying-methane-emissions-landfilled-food-waste\" target=\"_blank\" rel=\"noopener\">EPA Methan-Emissionen<\/a> aus deponierten Lebensmitteln.<\/p><\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-how-does-iso-20001-differ-from-iso-22000\">Worin unterscheidet sich ISO 20001 von ISO 22000?<\/h3>\n\n<p class=\"wp-block-paragraph\"><p><a href=\"https:\/\/www.iso.org\/iso-22000-food-safety-management.html\" target=\"_blank\" rel=\"noopener\">ISO 22000<\/a> umfasst die Lebensmittelsicherheit \u2013 Gefahrenanalyse, kritische Kontrollpunkte, Schutz der G\u00e4ste vor Kontamination. ISO 20001 umfasst Lebensmittelabf\u00e4lle \u2013 Vermeidung, Messung und Ressourceneffizienz.<\/p><\/p>\n\n<p class=\"wp-block-paragraph\">Die beiden Standards erg\u00e4nzen sich. ISO 20001 ist so konzipiert, dass er sich nahtlos mit anderen Managementsystemen wie ISO 9001 und ISO 22000 kombinieren l\u00e4sst. Wenn Ihr Betrieb also bereits ein ISO-zertifiziertes System nutzt, erfordert die Einf\u00fchrung von ISO 20001 keinen grundlegenden Umbau Ihrer Prozesse.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-what-does-iso-20001-mean-for-the-food-industry\">Was bedeutet ISO 20001 f\u00fcr die Lebensmittelbranche?<\/h2>\n\n<p class=\"wp-block-paragraph\">ISO 20001 f\u00fchrt eine gemeinsame Sprache f\u00fcr die Definition, Messung und Berichterstattung von Lebensmittelabf\u00e4llen ein.<\/p>\n\n<p class=\"wp-block-paragraph\">Derzeit misst ein Hotel Abf\u00e4lle nach Gewicht, ein anderes nach Abdeckungen, ein drittes nach Umsatzanteil. Das erschwert Investoren und Nachhaltigkeitsteams den Vergleich von Leistungen innerhalb eines Portfolios.<\/p>\n\n<p class=\"wp-block-paragraph\">ISO 20001 vereinfacht das: Die Norm legt einheitliche Definitionen, konsistente Kennzahlen und gemeinsame Best Practices in Sachen Lagerung, Transport, Verarbeitung und Verpackungen fest.<\/p>\n\n<p class=\"wp-block-paragraph\">Das bedeutet: Abf\u00e4lle vom Fr\u00fchst\u00fccksbuffet, von der Vorbereitung oder vom Teller werden wie bei allen Mitbewerbern nach denselben Standards gemessen.<\/p>\n\n<p class=\"wp-block-paragraph\">F\u00fcr Hotelgruppen und gro\u00dfe Hospitality-Marken ist diese Standardisierung ein echter Game Changer: Nachhaltigkeitsberichte werden einfacher, Benchmarking fairer und Fortschritte endlich mess- und vergleichbar.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-who-does-iso-20001-apply-to\">F\u00fcr wen gilt ISO 20001?<\/h2>\n\n<p class=\"wp-block-paragraph\">Die Norm richtet sich unabh\u00e4ngig von der Gr\u00f6\u00dfe oder Struktur an alle Unternehmen in der Lebensmittelkette. Sie gilt also f\u00fcr Hersteller, Transport- und Lagerbetriebe, Gro\u00dfh\u00e4ndler, Einzelh\u00e4ndler, Tafeln sowie Betriebe mit Gastronomie oder Catering.<\/p>\n\n<p class=\"wp-block-paragraph\">In der Praxis betrifft das:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Hotels mit eigenen F&amp;B-Bereichen \u2013 insbesondere jene mit Fr\u00fchst\u00fccksbuffets, wo Abf\u00e4lle am sichtbarsten sind<\/li>\n\n\n\n<li>Catering-Gruppen in Stadien, Flugh\u00e4fen, Firmencampussen oder Eventlocations<\/li>\n\n\n\n<li>Gesundheitseinrichtungen mit Gro\u00dfk\u00fcchen f\u00fcr Personal und Patienten<\/li>\n\n\n\n<li>Gro\u00dfe Restaurants oder Restaurantgruppen mit zentralisiertem Reporting<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">Wenn Ihr Betrieb t\u00e4glich mehr als 200 G\u00e4ste bedient oder mehrere Standorte unter einer Marke betreibt, gilt ISO 20001 f\u00fcr Sie.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-what-are-iso-20001-requirements\">Welche Anforderungen stellt ISO 20001?<\/h2>\n\n<p class=\"wp-block-paragraph\">Die endg\u00fcltige Norm ist noch nicht ver\u00f6ffentlicht, aber die Entw\u00fcrfe zeigen eine klare Richtung: Es geht um die Planung, Umsetzung und kontinuierliche Verbesserung eines Food Loss and Waste Management Systems.<\/p>\n\n<p class=\"wp-block-paragraph\">Die zentralen Elemente sind:<\/p>\n\n<ul class=\"wp-block-list\">\n<li><p><strong>F\u00fchrung &amp; Verantwortung:<\/strong> Das Management legt Richtlinien, Ziele und Ressourcen fest. Die Nachhaltigkeit darf keine reine Koordinatorenaufgabe bleiben.<\/p><\/li>\n\n\n\n<li><p><strong>Messung &amp; \u00dcberwachung:<\/strong> Abf\u00e4lle m\u00fcssen verl\u00e4sslich nach Gewicht, Kategorie und Quelle erfasst werden, damit die Daten einer Audit-Pr\u00fcfung standhalten.<\/p><\/li>\n\n\n\n<li><p><strong>Aktionspl\u00e4ne mit Verantwortlichkeiten:<\/strong> Es geht nicht nur um das Erkennen von Abf\u00e4llen. Ma\u00dfnahmen m\u00fcssen dokumentiert, Verantwortliche benannt und Ergebnisse \u00fcberpr\u00fcft werden.<\/p><\/li>\n\n\n\n<li><p><strong>Regelm\u00e4\u00dfige \u00dcberpr\u00fcfung und Berichterstattung:<\/strong> Management-Reviews werden zum Standard und werden zur Leistungsbewertung, Zielanpassung und Kommunikation mit Stakeholdern genutzt.<\/p><\/li>\n\n\n\n<li><p><strong>Kontinuierliche Verbesserung:<\/strong> Wie andere ISO-Managementsysteme folgt auch ISO 20001 dem Plan-Do-Check-Act-Zyklus. Es werden Fortschritte erwartet.<\/p><\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\" id=\"h-how-businesses-can-prepare-now-for-iso-20001\">Wie sich Unternehmen schon jetzt auf ISO 20001 vorbereiten k\u00f6nnen<\/h2>\n\n<p class=\"wp-block-paragraph\">Viele Anforderungen zeichnen sich bereits ab, sodass Sie jetzt mit der Vorbereitung beginnen k\u00f6nnen.<\/p>\n\n<ol class=\"wp-block-list\">\n<li><p><strong>Zuverl\u00e4ssige Messsysteme installieren:<\/strong> Die manuelle Erfassung h\u00e4lt auf Dauer nicht stand und Auditoren akzeptieren keine inkonsistenten Daten. Automatisiertes Tracking beseitigt R\u00e4tselraten und liefert die belastbare Datengrundlage f\u00fcr Ihre Zertifizierung.<br\/>Orbisk unterst\u00fctzt Sie dabei, <a href=\"https:\/\/orbisk.com\/de\/produkt\/so-funktionierts\/\" target=\"_blank\" rel=\"noopener\">Lebensmittelabf\u00e4lle ab dem ersten Tag automatisch mit einem \u00dcberblick und verifizierbaren Daten nach Gewicht und Kategorie zu erfassen.<\/a><\/p><\/li>\n\n\n\n<li><p><strong>Definitionen standort\u00fcbergreifend vereinheitlichen:<\/strong> \u201eLebensmittelabfall\u201c sollte \u00fcberall dasselbe bedeuten. Definieren Sie klar, was Vorbereitungs-, Teller- und Buffetabf\u00e4lle sind und wenden Sie diese Definitionen einheitlich an.<\/p><\/li>\n\n\n\n<li><p><strong>Klare Verantwortlichkeiten schaffen:<\/strong> Eine erfahrene F\u00fchrungskraft sollte f\u00fcr das System verantwortlich sein. Wenn Verantwortung zu breit verteilt ist, verliert das Thema schnell an Priorit\u00e4t.<\/p><\/li>\n\n\n\n<li><p><strong>Baseline-Daten erheben:<\/strong> Ohne Ausgangspunkt ist kein Fortschritt m\u00f6glich. Messen Sie den Gesamtabfall, den Abfall pro Abdeckung und den Abfall nach Kategorie, bevor Sie \u00c4nderungen einf\u00fchren. Mit Orbisk erreichen Teams in <a href=\"https:\/\/orbisk.com\/blog\/success-story-raffles-hotel-singapore\/\" target=\"_blank\" rel=\"noopener\">nur sechs Wochen eine belastbare Basis<\/a>.<\/p><\/li>\n\n\n\n<li><p><strong>Klein starten, dann skalieren: <\/strong>Beginnen Sie mit einem Standort oder einer Station. Testen Sie, dokumentieren Sie, was funktioniert, und verfeinern Sie den Ansatz vor dem Rollout im gesamten Betrieb.<\/p><\/li>\n<\/ol>\n\n<h2 class=\"wp-block-heading\" id=\"h-recommended-kpis-amp-metrics-to-track-for-readiness-and-reporting\">Empfohlene KPIs und Kennzahlen zur Vorbereitung und Berichterstattung<\/h2>\n\n<p class=\"wp-block-paragraph\">Zur Erf\u00fcllung von ISO 20001 brauchen Sie konsistente, messbare und pr\u00fcfbare Daten. Das hei\u00dft, Abf\u00e4lle m\u00fcssen strukturiert und wiederholbar erfasst werden. Es geht nicht blo\u00df darum, Zahlen zu sammeln, sondern aussagekr\u00e4ftige KPIs aufzubauen, die den Fortschritt und die Wirkung belegen. Zum Beispiel:<\/p>\n\n<ul class=\"wp-block-list\">\n<li><p><strong>Gesamter Lebensmittelabfall:<\/strong> Ermitteln Sie, wie viele Kilogramm Lebensmittel t\u00e4glich oder w\u00f6chentlich entsorgt werden. Mit Orbisk gen\u00fcgt ein Foto, bevor der Abfall in den Beh\u00e4lter geht. Diese Zahl ist f\u00fcr Stakeholder meist die erste relevante Kennzahl.<\/p><\/li>\n\n\n\n<li><p><strong>Abfall pro Abdeckung:<\/strong> Teilen Sie den Gesamtabfall durch die Zahl der servierten G\u00e4ste, um Daten zwischen Standorten vergleichbar zu machen.<\/p><\/li>\n\n\n\n<li><p><strong>Abfall nach Abfallstrom:<\/strong> Unterscheiden Sie nach Vorbereitung (K\u00fcchenabschnitte), Tellerresten (G\u00e4ste) und Buffetabf\u00e4llen (nicht servierte Speisen). Jeder Strom hat andere Ursachen und verlangt andere L\u00f6sungen. Orbisk kategorisiert diese automatisch f\u00fcr Sie.<\/p><\/li>\n\n\n\n<li><p><strong>Ma\u00dfnahmen &amp; Wirkung:<\/strong> Dokumentieren Sie, was ge\u00e4ndert wurde. Dazu geh\u00f6ren beispielsweise Portionsgr\u00f6\u00dfen, das Buffet-Layout oder der Einkauf und welche Ergebnisse erzielt wurden. Auditoren pr\u00fcfen, ob Ihre Ma\u00dfnahmen messbare Wirkung zeigen.<\/p><\/li>\n\n\n\n<li><p><strong>Monatliche Trendlinien:<\/strong> Einzelne Datenpunkte zeigen keine Entwicklung. Beobachten Sie die Performance im Zeitverlauf, um Fortschritte oder eine Stagnation zu erkennen.<\/p><\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">Einige Teams messen zus\u00e4tzlich den Abfallanteil am gesamten Lebensmitteleinkauf oder berechnen die Kosten des entsorgten Essens. Diese Kennzahlen helfen bei internen Business Cases, w\u00e4hrend das gewichtbasierte Tracking besser zu regulatorischen Anforderungen und Nachhaltigkeitsstandards passt.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-get-ready-for-iso-20001\">Vorbereitung auf ISO 20001<\/h2>\n\n<p class=\"wp-block-paragraph\">ISO 20001 wird k\u00fcnftig beeinflussen, wie Unternehmen weltweit Lebensmittelabf\u00e4lle messen und managen. Anstelle von Sch\u00e4tzungen oder uneinheitlichen Methoden verlangt der Standard verl\u00e4ssliche, vergleichbare Daten.<\/p>\n\n<p class=\"wp-block-paragraph\">K\u00fcchenteams m\u00fcssen nicht warten. Der erste Schritt ist Transparenz: zu wissen, was wann und warum entsorgt wird. Diese Erkenntnisse machen es leichter, den Einkauf, die Portionierung und die Produktion ohne Kompromisse beim Service zu optimieren.<\/p>\n\n<p class=\"wp-block-paragraph\"><p>Orbisk hilft K\u00fcchen genau dabei, indem es <a href=\"https:\/\/orbisk.com\/de\/produkt\/angebote\/\" target=\"_blank\" rel=\"noopener\">Lebensmittelabf\u00e4lle ohne manuelle Eingaben oder Schulungsaufwand automatisch erfasst und kategorisiert<\/a>. So kann sich Ihr Team auf Verbesserungen konzentrieren, statt mit der Datenerfassung besch\u00e4ftigt zu sein.<\/p><\/p>\n\n \n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-faq\">H\u00e4ufig gestellte Fragen<\/h2>\n\n<p class=\"wp-block-paragraph\"><p><strong>Ist ISO 20001 bereits ver\u00f6ffentlicht und zertifizierbar?<\/strong><br\/>Nein. ISO 20001 befindet sich derzeit in der Committee Draft 2-Phase und wird bald als Draft International Standard ver\u00f6ffentlicht. Die finale Norm wird voraussichtlich 2027 erscheinen. Kurz darauf beginnen Zertifizierungsstellen mit Audits.<\/p><\/p>\n\n<p class=\"wp-block-paragraph\"><p><strong>Worin unterscheidet sich ISO 20001 von ISO 22000 oder anderen ISO-Normen?<\/strong><br\/>ISO 22000 konzentriert sich auf die Lebensmittelsicherheit. ISO 20001 konzentriert sich auf Lebensmittelabf\u00e4lle. Die Norm ist so gestaltet, dass sie sich nahtlos mit Standards wie ISO 22000, ISO 9001 und ISO 14001 kombinieren l\u00e4sst. Dank der vertrauten Struktur k\u00f6nnen bereits zertifizierte Betriebe ISO 20001 problemlos integrieren.<\/p><\/p>\n\n<p class=\"wp-block-paragraph\"><p><strong>Was sind die ersten Schritte, um sich auf ISO 20001 auszurichten?<\/strong><br\/>Beginnen Sie mit der pr\u00e4zisen Erfassung Ihrer Abf\u00e4lle. Verwenden Sie Systeme, die nach Gewicht und Kategorie messen und stellen Sie sicher, dass alle Standorte dieselben Kennzahlen nutzen. Ermitteln Sie anschlie\u00dfend eine Baseline, testen Sie erste Ma\u00dfnahmen an einem Standort und dokumentieren Sie alles, damit Sie bei k\u00fcnftigen Audits belastbare Nachweise haben.<\/p><\/p>\n\n<script type=\"application\/ld+json\">\r\n{\r\n  \"@context\": \"https:\/\/schema.org\",\r\n  \"@type\": \"FAQPage\",\r\n  \"mainEntity\": [\r\n    {\r\n      \"@type\": \"Question\",\r\n      \"name\": \"Ist ISO 20001 bereits ver\u00f6ffentlicht und zertifizierbar?\",\r\n      \"acceptedAnswer\": {\r\n        \"@type\": \"Answer\",\r\n        \"text\": \"Nein. ISO 20001 befindet sich derzeit in der Committee Draft 2-Phase und wird bald als Draft International Standard ver\u00f6ffentlicht. Die finale Norm wird voraussichtlich 2027 erscheinen. Kurz darauf beginnen Zertifizierungsstellen mit Audits.\"\r\n      }\r\n    },\r\n    {\r\n      \"@type\": \"Question\",\r\n      \"name\": \"Worin unterscheidet sich ISO 20001 von ISO 22000 oder anderen ISO-Normen?\",\r\n      \"acceptedAnswer\": {\r\n        \"@type\": \"Answer\",\r\n        \"text\": \"ISO 22000 konzentriert sich auf die Lebensmittelsicherheit. ISO 20001 konzentriert sich auf Lebensmittelabf\u00e4lle. Die Norm ist so gestaltet, dass sie sich nahtlos mit Standards wie ISO 22000, ISO 9001 und ISO 14001 kombinieren l\u00e4sst. Dank der vertrauten Struktur k\u00f6nnen bereits zertifizierte Betriebe ISO 20001 problemlos integrieren.\"\r\n      }\r\n    },\r\n    {\r\n      \"@type\": \"Question\",\r\n      \"name\": \"Was sind die ersten Schritte, um sich auf ISO 20001 auszurichten?\",\r\n      \"acceptedAnswer\": {\r\n        \"@type\": \"Answer\",\r\n        \"text\": \"Beginnen Sie mit der pr\u00e4zisen Erfassung Ihrer Abf\u00e4lle. Verwenden Sie Systeme, die nach Gewicht und Kategorie messen, und stellen Sie sicher, dass alle Standorte dieselben Kennzahlen nutzen. Ermitteln Sie anschlie\u00dfend eine Baseline, testen Sie erste Ma\u00dfnahmen an einem Standort und dokumentieren Sie alles, damit Sie bei k\u00fcnftigen Audits belastbare Nachweise haben.\"\r\n      }\r\n    }\r\n  ]\r\n}\r\n<\/script>\n","protected":false},"excerpt":{"rendered":"<p>Lebensmittelverschwendung ist l\u00e4ngst kein reines Nachhaltigkeitsthema mehr, sondern wird zunehmend zu einer regulierten gesch\u00e4ftlichen Priorit\u00e4t. W\u00e4hrend Regierungen Ziele vorgeben und Hersteller unter Druck stehen, nachweisbare Fortschritte zu zeigen, suchen Unternehmen nach einer einheitlichen Methode, um ihre Leistung im Bereich Lebensmittelabf\u00e4lle zu messen und zu steuern. Hier kommt ISO 20001 ins Spiel. Diese kommende Norm bietet [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":25546841,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[74],"tags":[],"dipi_cpt_category":[],"class_list":["post-25547339","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lebensmittel-fakten-und-zahlen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Alles Wissenswerte \u00fcber die ISO 20001-Standards f\u00fcr Lebensmittelabf\u00e4lle<\/title>\n<meta name=\"description\" content=\"Erfahren Sie, was die ISO 20001-Normen f\u00fcr Lebensmittelabf\u00e4lle beinhalten, f\u00fcr wen sie gelten und wie Sie sich mit Mess- und Berichtssystemen auf die Einf\u00fchrung vorbereiten k\u00f6nnen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orbisk.com\/de\/blog\/alles-wissenswerte-ueber-die-iso-20001-standards-fuer-lebensmittelabfaelle\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alles Wissenswerte \u00fcber die ISO 20001-Standards f\u00fcr Lebensmittelabf\u00e4lle\" \/>\n<meta property=\"og:description\" content=\"Erfahren Sie, was die ISO 20001-Normen f\u00fcr Lebensmittelabf\u00e4lle beinhalten, f\u00fcr wen sie gelten und wie Sie sich mit Mess- und Berichtssystemen auf die Einf\u00fchrung vorbereiten k\u00f6nnen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orbisk.com\/de\/blog\/alles-wissenswerte-ueber-die-iso-20001-standards-fuer-lebensmittelabfaelle\/\" \/>\n<meta property=\"og:site_name\" content=\"Orbisk\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Orbiskzerofoodwaste\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-10T15:10:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-30T12:48:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/orbisk.com\/wp-content\/uploads\/2025\/12\/ISO-20001-blog-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hakon Kleppe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hakon Kleppe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/orbisk.com\\\/de\\\/blog\\\/alles-wissenswerte-ueber-die-iso-20001-standards-fuer-lebensmittelabfaelle\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orbisk.com\\\/de\\\/blog\\\/alles-wissenswerte-ueber-die-iso-20001-standards-fuer-lebensmittelabfaelle\\\/\"},\"author\":{\"name\":\"Hakon Kleppe\",\"@id\":\"https:\\\/\\\/orbisk.com\\\/de\\\/#\\\/schema\\\/person\\\/040cbd504181af7e4bdf0ef1470a75e7\"},\"headline\":\"Alles Wissenswerte \u00fcber die ISO 20001-Standards f\u00fcr Lebensmittelabf\u00e4lle\",\"datePublished\":\"2025-12-10T15:10:56+00:00\",\"dateModified\":\"2026-01-30T12:48:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/orbisk.com\\\/de\\\/blog\\\/alles-wissenswerte-ueber-die-iso-20001-standards-fuer-lebensmittelabfaelle\\\/\"},\"wordCount\":1445,\"publisher\":{\"@id\":\"https:\\\/\\\/orbisk.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/orbisk.com\\\/de\\\/blog\\\/alles-wissenswerte-ueber-die-iso-20001-standards-fuer-lebensmittelabfaelle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orbisk.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ISO-20001-blog-scaled.jpg\",\"articleSection\":[\"Lebensmittel Fakten &amp; Zahlen\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/orbisk.com\\\/de\\\/blog\\\/alles-wissenswerte-ueber-die-iso-20001-standards-fuer-lebensmittelabfaelle\\\/\",\"url\":\"https:\\\/\\\/orbisk.com\\\/de\\\/blog\\\/alles-wissenswerte-ueber-die-iso-20001-standards-fuer-lebensmittelabfaelle\\\/\",\"name\":\"Alles Wissenswerte \u00fcber die ISO 20001-Standards f\u00fcr Lebensmittelabf\u00e4lle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orbisk.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/orbisk.com\\\/de\\\/blog\\\/alles-wissenswerte-ueber-die-iso-20001-standards-fuer-lebensmittelabfaelle\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/orbisk.com\\\/de\\\/blog\\\/alles-wissenswerte-ueber-die-iso-20001-standards-fuer-lebensmittelabfaelle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orbisk.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ISO-20001-blog-scaled.jpg\",\"datePublished\":\"2025-12-10T15:10:56+00:00\",\"dateModified\":\"2026-01-30T12:48:22+00:00\",\"description\":\"Erfahren Sie, was die ISO 20001-Normen f\u00fcr Lebensmittelabf\u00e4lle beinhalten, f\u00fcr wen sie gelten und wie Sie sich mit Mess- und Berichtssystemen auf die Einf\u00fchrung vorbereiten k\u00f6nnen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/orbisk.com\\\/de\\\/blog\\\/alles-wissenswerte-ueber-die-iso-20001-standards-fuer-lebensmittelabfaelle\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/orbisk.com\\\/de\\\/blog\\\/alles-wissenswerte-ueber-die-iso-20001-standards-fuer-lebensmittelabfaelle\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/orbisk.com\\\/de\\\/blog\\\/alles-wissenswerte-ueber-die-iso-20001-standards-fuer-lebensmittelabfaelle\\\/#primaryimage\",\"url\":\"https:\\\/\\\/orbisk.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ISO-20001-blog-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/orbisk.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ISO-20001-blog-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"ISO 20001 blog\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/orbisk.com\\\/de\\\/blog\\\/alles-wissenswerte-ueber-die-iso-20001-standards-fuer-lebensmittelabfaelle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/orbisk.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unkategorisiert\",\"item\":\"https:\\\/\\\/orbisk.com\\\/de\\\/blog\\\/category\\\/unkategorisiert\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Alles Wissenswerte \u00fcber die ISO 20001-Standards f\u00fcr Lebensmittelabf\u00e4lle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/orbisk.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/orbisk.com\\\/de\\\/\",\"name\":\"Orbisk - Zero Food Waste\",\"description\":\"Zero Food Waste\",\"publisher\":{\"@id\":\"https:\\\/\\\/orbisk.com\\\/de\\\/#organization\"},\"alternateName\":\"Orbisk\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/orbisk.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/orbisk.com\\\/de\\\/#organization\",\"name\":\"Orbisk\",\"url\":\"https:\\\/\\\/orbisk.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/orbisk.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/orbisk.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Orbisk-logo.png\",\"contentUrl\":\"https:\\\/\\\/orbisk.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Orbisk-logo.png\",\"width\":500,\"height\":385,\"caption\":\"Orbisk\"},\"image\":{\"@id\":\"https:\\\/\\\/orbisk.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Orbiskzerofoodwaste\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/18624102\\\/\",\"https:\\\/\\\/www.instagram.com\\\/orbisk\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/orbisk.com\\\/de\\\/#\\\/schema\\\/person\\\/040cbd504181af7e4bdf0ef1470a75e7\",\"name\":\"Hakon Kleppe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/76b27059a6a58f0d980086cbe493a41b429d1d9fef0bf863d4b8f6ca38cef840?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/76b27059a6a58f0d980086cbe493a41b429d1d9fef0bf863d4b8f6ca38cef840?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/76b27059a6a58f0d980086cbe493a41b429d1d9fef0bf863d4b8f6ca38cef840?s=96&d=mm&r=g\",\"caption\":\"Hakon Kleppe\"},\"url\":\"https:\\\/\\\/orbisk.com\\\/de\\\/blog\\\/author\\\/hakon\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Alles Wissenswerte \u00fcber die ISO 20001-Standards f\u00fcr Lebensmittelabf\u00e4lle","description":"Erfahren Sie, was die ISO 20001-Normen f\u00fcr Lebensmittelabf\u00e4lle beinhalten, f\u00fcr wen sie gelten und wie Sie sich mit Mess- und Berichtssystemen auf die Einf\u00fchrung vorbereiten k\u00f6nnen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orbisk.com\/de\/blog\/alles-wissenswerte-ueber-die-iso-20001-standards-fuer-lebensmittelabfaelle\/","og_locale":"de_DE","og_type":"article","og_title":"Alles Wissenswerte \u00fcber die ISO 20001-Standards f\u00fcr Lebensmittelabf\u00e4lle","og_description":"Erfahren Sie, was die ISO 20001-Normen f\u00fcr Lebensmittelabf\u00e4lle beinhalten, f\u00fcr wen sie gelten und wie Sie sich mit Mess- und Berichtssystemen auf die Einf\u00fchrung vorbereiten k\u00f6nnen.","og_url":"https:\/\/orbisk.com\/de\/blog\/alles-wissenswerte-ueber-die-iso-20001-standards-fuer-lebensmittelabfaelle\/","og_site_name":"Orbisk","article_publisher":"https:\/\/www.facebook.com\/Orbiskzerofoodwaste\/","article_published_time":"2025-12-10T15:10:56+00:00","article_modified_time":"2026-01-30T12:48:22+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/orbisk.com\/wp-content\/uploads\/2025\/12\/ISO-20001-blog-scaled.jpg","type":"image\/jpeg"}],"author":"Hakon Kleppe","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Hakon Kleppe","Gesch\u00e4tzte Lesezeit":"7 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/orbisk.com\/de\/blog\/alles-wissenswerte-ueber-die-iso-20001-standards-fuer-lebensmittelabfaelle\/#article","isPartOf":{"@id":"https:\/\/orbisk.com\/de\/blog\/alles-wissenswerte-ueber-die-iso-20001-standards-fuer-lebensmittelabfaelle\/"},"author":{"name":"Hakon Kleppe","@id":"https:\/\/orbisk.com\/de\/#\/schema\/person\/040cbd504181af7e4bdf0ef1470a75e7"},"headline":"Alles Wissenswerte \u00fcber die ISO 20001-Standards f\u00fcr Lebensmittelabf\u00e4lle","datePublished":"2025-12-10T15:10:56+00:00","dateModified":"2026-01-30T12:48:22+00:00","mainEntityOfPage":{"@id":"https:\/\/orbisk.com\/de\/blog\/alles-wissenswerte-ueber-die-iso-20001-standards-fuer-lebensmittelabfaelle\/"},"wordCount":1445,"publisher":{"@id":"https:\/\/orbisk.com\/de\/#organization"},"image":{"@id":"https:\/\/orbisk.com\/de\/blog\/alles-wissenswerte-ueber-die-iso-20001-standards-fuer-lebensmittelabfaelle\/#primaryimage"},"thumbnailUrl":"https:\/\/orbisk.com\/wp-content\/uploads\/2025\/12\/ISO-20001-blog-scaled.jpg","articleSection":["Lebensmittel Fakten &amp; Zahlen"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/orbisk.com\/de\/blog\/alles-wissenswerte-ueber-die-iso-20001-standards-fuer-lebensmittelabfaelle\/","url":"https:\/\/orbisk.com\/de\/blog\/alles-wissenswerte-ueber-die-iso-20001-standards-fuer-lebensmittelabfaelle\/","name":"Alles Wissenswerte \u00fcber die ISO 20001-Standards f\u00fcr Lebensmittelabf\u00e4lle","isPartOf":{"@id":"https:\/\/orbisk.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/orbisk.com\/de\/blog\/alles-wissenswerte-ueber-die-iso-20001-standards-fuer-lebensmittelabfaelle\/#primaryimage"},"image":{"@id":"https:\/\/orbisk.com\/de\/blog\/alles-wissenswerte-ueber-die-iso-20001-standards-fuer-lebensmittelabfaelle\/#primaryimage"},"thumbnailUrl":"https:\/\/orbisk.com\/wp-content\/uploads\/2025\/12\/ISO-20001-blog-scaled.jpg","datePublished":"2025-12-10T15:10:56+00:00","dateModified":"2026-01-30T12:48:22+00:00","description":"Erfahren Sie, was die ISO 20001-Normen f\u00fcr Lebensmittelabf\u00e4lle beinhalten, f\u00fcr wen sie gelten und wie Sie sich mit Mess- und Berichtssystemen auf die Einf\u00fchrung vorbereiten k\u00f6nnen.","breadcrumb":{"@id":"https:\/\/orbisk.com\/de\/blog\/alles-wissenswerte-ueber-die-iso-20001-standards-fuer-lebensmittelabfaelle\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orbisk.com\/de\/blog\/alles-wissenswerte-ueber-die-iso-20001-standards-fuer-lebensmittelabfaelle\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/orbisk.com\/de\/blog\/alles-wissenswerte-ueber-die-iso-20001-standards-fuer-lebensmittelabfaelle\/#primaryimage","url":"https:\/\/orbisk.com\/wp-content\/uploads\/2025\/12\/ISO-20001-blog-scaled.jpg","contentUrl":"https:\/\/orbisk.com\/wp-content\/uploads\/2025\/12\/ISO-20001-blog-scaled.jpg","width":2560,"height":1707,"caption":"ISO 20001 blog"},{"@type":"BreadcrumbList","@id":"https:\/\/orbisk.com\/de\/blog\/alles-wissenswerte-ueber-die-iso-20001-standards-fuer-lebensmittelabfaelle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orbisk.com\/de\/"},{"@type":"ListItem","position":2,"name":"Unkategorisiert","item":"https:\/\/orbisk.com\/de\/blog\/category\/unkategorisiert\/"},{"@type":"ListItem","position":3,"name":"Alles Wissenswerte \u00fcber die ISO 20001-Standards f\u00fcr Lebensmittelabf\u00e4lle"}]},{"@type":"WebSite","@id":"https:\/\/orbisk.com\/de\/#website","url":"https:\/\/orbisk.com\/de\/","name":"Orbisk - Zero Food Waste","description":"Zero Food Waste","publisher":{"@id":"https:\/\/orbisk.com\/de\/#organization"},"alternateName":"Orbisk","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orbisk.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/orbisk.com\/de\/#organization","name":"Orbisk","url":"https:\/\/orbisk.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/orbisk.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/orbisk.com\/wp-content\/uploads\/2023\/02\/Orbisk-logo.png","contentUrl":"https:\/\/orbisk.com\/wp-content\/uploads\/2023\/02\/Orbisk-logo.png","width":500,"height":385,"caption":"Orbisk"},"image":{"@id":"https:\/\/orbisk.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Orbiskzerofoodwaste\/","https:\/\/www.linkedin.com\/company\/18624102\/","https:\/\/www.instagram.com\/orbisk\/"]},{"@type":"Person","@id":"https:\/\/orbisk.com\/de\/#\/schema\/person\/040cbd504181af7e4bdf0ef1470a75e7","name":"Hakon Kleppe","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/76b27059a6a58f0d980086cbe493a41b429d1d9fef0bf863d4b8f6ca38cef840?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/76b27059a6a58f0d980086cbe493a41b429d1d9fef0bf863d4b8f6ca38cef840?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/76b27059a6a58f0d980086cbe493a41b429d1d9fef0bf863d4b8f6ca38cef840?s=96&d=mm&r=g","caption":"Hakon Kleppe"},"url":"https:\/\/orbisk.com\/de\/blog\/author\/hakon\/"}]}},"modified_by":null,"_links":{"self":[{"href":"https:\/\/orbisk.com\/de\/wp-json\/wp\/v2\/posts\/25547339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orbisk.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/orbisk.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/orbisk.com\/de\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/orbisk.com\/de\/wp-json\/wp\/v2\/comments?post=25547339"}],"version-history":[{"count":0,"href":"https:\/\/orbisk.com\/de\/wp-json\/wp\/v2\/posts\/25547339\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orbisk.com\/de\/wp-json\/wp\/v2\/media\/25546841"}],"wp:attachment":[{"href":"https:\/\/orbisk.com\/de\/wp-json\/wp\/v2\/media?parent=25547339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/orbisk.com\/de\/wp-json\/wp\/v2\/categories?post=25547339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/orbisk.com\/de\/wp-json\/wp\/v2\/tags?post=25547339"},{"taxonomy":"dipi_cpt_category","embeddable":true,"href":"https:\/\/orbisk.com\/de\/wp-json\/wp\/v2\/dipi_cpt_category?post=25547339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}