{"id":25547356,"date":"2026-01-12T16:57:35","date_gmt":"2026-01-12T16:57:35","guid":{"rendered":"https:\/\/orbisk.com\/blog\/qa-mit-anastasia-dellis-geschaeftsfuehrerin-von-orbisk\/"},"modified":"2026-02-25T08:17:03","modified_gmt":"2026-02-25T08:17:03","slug":"qa-mit-anastasia-dellis-geschaeftsfuehrerin-von-orbisk","status":"publish","type":"post","link":"https:\/\/orbisk.com\/de\/blog\/qa-mit-anastasia-dellis-geschaeftsfuehrerin-von-orbisk\/","title":{"rendered":"Q&#038;A mit Anastasia Dellis, Gesch\u00e4ftsf\u00fchrerin von Orbisk"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\" id=\"h-on-the-zero-waste-mission-global-ambition-and-why-asia-pacific-is-next\">\u00dcber die Zero-Waste-Mission, globale Ambitionen und warum der asiatisch-pazifische Raum als N\u00e4chstes folgt<\/h1>\n\n<h2 class=\"wp-block-heading\" id=\"h-orbisk-s-vision-amp-momentum\"><p><strong>Orbisks Vision und Dynamik<\/strong><\/p><\/h2>\n\n<h3 class=\"wp-block-heading\" id=\"h-orbisk-has-grown-rapidly-in-recent-years-how-do-you-describe-the-company-s-focus-today\"><p><strong>Orbisk ist in den letzten Jahren stark gewachsen. Wie w\u00fcrden Sie heute den Fokus des Unternehmens beschreiben?<\/strong><\/p><\/h3>\n\n<p class=\"wp-block-paragraph\">Orbisk verfolgt ein klares Ziel: Lebensmittelabf\u00e4lle zu eliminieren und durch unsere weltweite F\u00fchrungsrolle im Bereich Food-Waste-Intelligence ein klimaneutrales Lebensmittelsystem zu erm\u00f6glichen.<\/p>\n\n<p class=\"wp-block-paragraph\">In den vergangenen Jahren haben wir gezeigt, dass die Reduzierung von Lebensmittelabf\u00e4llen nicht nur eine Nachhaltigkeitsma\u00dfnahme ist, sondern ein echter Leistungshebel. Wenn K\u00fcchen ihre Abf\u00e4lle richtig messen, sparen sie Kosten, steigern ihre Effizienz und treffen t\u00e4glich bessere Entscheidungen.<\/p>\n\n<p class=\"wp-block-paragraph\">Heute liegt unser Fokus darauf, diese Wirkung zu skalieren. Das bedeutet: mit einer Technologie, die \u00fcber unterschiedliche K\u00fcchenstile, Formate und betriebliche Realit\u00e4ten funktioniert, noch mehr Betriebe in mehr Regionen zu unterst\u00fctzen.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-what-does-global-leadership-mean-to-you-in-practice\"><p><strong>Was bedeutet \u201eweltweite F\u00fchrungsrolle\u201c f\u00fcr Sie ganz konkret?<\/strong><\/p><\/h3>\n\n<p class=\"wp-block-paragraph\">Weltweite F\u00fchrungsrolle bedeutet, \u00fcberall dort relevant zu sein, wo wir aktiv sind. F\u00fcr Orbisk hei\u00dft das, eine starke lokale Umsetzung mit einer konsistenten, datenbasierten Plattform zu verbinden, auf die sich unsere Kunden aus der ganzen Welt verlassen k\u00f6nnen.<\/p>\n\n<p class=\"wp-block-paragraph\">Gleichzeitig geht es darum, die Expertise im gro\u00dfen Ma\u00dfstab aufzubauen. Je mehr professionelle K\u00fcchen wir unterst\u00fctzen, desto besser werden unsere Einblicke. Davon profitieren unsere Kunden unabh\u00e4ngig von ihren Standorten.<\/p>\n\n<hr class=\"wp-block-separator aligncenter has-alpha-channel-opacity is-style-wide\"\/>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-why-asia-pacific-why-now-nbsp\"><p><strong>Warum Asien-Pazifik \u2013 und warum jetzt?<\/strong><\/p><\/h2>\n\n<h3 class=\"wp-block-heading\" id=\"h-why-is-asia-pacific-such-an-important-region-for-orbisk-s-next-phase-of-growth\"><p><strong>Warum ist der asiatisch-pazifische Raum f\u00fcr Orbisks n\u00e4chste Wachstumsphase so wichtig?<\/strong><\/p><\/h3>\n\n<p class=\"wp-block-paragraph\">Der asiatisch-pazifische Raum ist die am schnellsten wachsende Foodservice-Region der Welt. Betriebe skalieren rasant, w\u00e4hrend die Lebensmittelkosten steigen und die Anforderungen an Nachhaltigkeit und das Berichtswesen zunehmen.<\/p>\n\n<p class=\"wp-block-paragraph\">Gleichzeitig verursacht APAC den gr\u00f6\u00dften Anteil der weltweiten Lebensmittelabf\u00e4lle. Regierungen in M\u00e4rkten wie Singapur f\u00fchren klare Vorgaben zur Messung und Reduzierung von Abf\u00e4llen ein und Betreiber suchen aktiv nach L\u00f6sungen, um diesen Anforderungen einen Schritt voraus zu sein.<\/p>\n\n<p class=\"wp-block-paragraph\">F\u00fcr Orbisk ist APAC daher eine Region, in der Wirkung, Nachfrage und Umsetzungsbereitschaft besonders gut zusammenkommen.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-what-challenges-do-food-service-operators-in-apac-face-today\"><p><strong>Vor welchen Herausforderungen stehen Foodservice-Betreiber in APAC heute?<\/strong><\/p><\/h3>\n\n<p class=\"wp-block-paragraph\">Viele Betriebe m\u00fcssen Wachstum mit zunehmendem Margendruck in Einklang bringen. Komplexe Men\u00fcs und vielf\u00e4ltige K\u00fcchenstile im gro\u00dfen Ma\u00dfstab zu managen, geht heute Hand in Hand mit der Erwartung, Kosten zu senken und Nachhaltigkeitsleistungen transparent und messbar zu gestalten.<\/p>\n\n<p class=\"wp-block-paragraph\">Ohne klare Daten bleiben Lebensmittelabf\u00e4lle unsichtbar. Und was unsichtbar ist, l\u00e4sst sich kaum steuern. Genau hier setzt Orbisk mit Klarheit, Struktur und konkreten L\u00f6sungen direkt auf K\u00fcchenniveau an.<\/p>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-what-orbisk-brings-to-the-region-nbsp\"><p><strong>Was Orbisk in die Region bringt<\/strong><\/p><\/h2>\n\n<h3 class=\"wp-block-heading\" id=\"h-how-does-orbisk-support-operators-as-they-scale-in-apac\"><p><strong>Wie unterst\u00fctzt Orbisk Betreiber bei ihrem Wachstum in APAC?<\/strong><\/p><\/h3>\n\n<p class=\"wp-block-paragraph\">Orbisk hilft Betreibern dabei, Abfalldaten in t\u00e4gliche betriebliche Entscheidungen zu \u00fcbersetzen. Unsere Plattform liefert K\u00fcchenteams klare Einblicke, umsetzbare Berichte f\u00fcr das Management und messbare Ergebnisse \u2013 und das \u00fcber mehrere Standorte hinweg.<\/p>\n\n<p class=\"wp-block-paragraph\">Wichtig dabei: Die L\u00f6sung passt sich lokalen K\u00fcchenstilen und Arbeitsabl\u00e4ufen an. Lebensmittelabf\u00e4lle in einem Hotel in Singapur zu reduzieren, sieht anders aus als in Europa. Deshalb h\u00f6ren wir kontinuierlich auf das Feedback unserer Kunden und entwickeln die Technologie entlang realer betrieblicher Anforderungen weiter.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-what-does-orbisk-s-expansion-mean-for-international-brands-operating-across-regions\"><p><strong>Was bedeutet Orbisks Expansion f\u00fcr internationale Marken in mehreren Regionen?<\/strong><\/p><\/h3>\n\n<p class=\"wp-block-paragraph\">Orbisk steht f\u00fcr Konsistenz, egal ob regional oder auf weltweiter Ebene. Wir haben einen einheitlichen Ansatz zur Messung und Reduzierung von Lebensmittelabf\u00e4llen, der von einer globalen Plattform mit lokal relevanten Einblicken getragen wird.<\/p>\n\n<p class=\"wp-block-paragraph\">So k\u00f6nnen Betreiber Leistungen standort\u00fcbergreifend vergleichen, bew\u00e4hrte Praktiken effizient ausrollen und Nachhaltigkeitsziele ohne zus\u00e4tzliche betriebliche Komplexit\u00e4t mit finanzieller Performance verbinden.<\/p>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-looking-ahead-where-orbisk-is-going-next-nbsp\"><p><strong>Ausblick: In welche Richtung sich Orbisk als N\u00e4chstes entwickelt<\/strong><\/p><\/h2>\n\n<h3 class=\"wp-block-heading\" id=\"h-how-do-you-see-orbisk-evolving-over-the-next-few-years\"><p><strong>Wie sehen Sie die Entwicklung von Orbisk in den kommenden Jahren?<\/strong><\/p><\/h3>\n\n<p class=\"wp-block-paragraph\">Orbisk entwickelt sich von einem schnell wachsenden europ\u00e4ischen Marktf\u00fchrer zu einer wirklich globalen Referenzplattform f\u00fcr Food-Waste-Intelligence.<\/p>\n\n<p class=\"wp-block-paragraph\">Das bedeutet: st\u00e4rkere regionale Pr\u00e4senz, engere Partnerschaften und kontinuierliche Investitionen in KI, Daten und Produktinnovation. Mit wachsender Datenbasis steigt auch der Mehrwert, den wir unseren Kunden bieten.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-what-does-success-in-apac-look-like-for-orbisk\"><p><strong>Wie sieht Erfolg f\u00fcr Orbisk im asiatisch-pazifischen Raum aus?<\/strong><\/p><\/h3>\n\n<p class=\"wp-block-paragraph\">Erfolg bedeutet, dass unsere Kunden echte, messbare Ergebnisse sehen: weniger Lebensmittelabf\u00e4lle, geringere Kosten und verl\u00e4ssliches Nachhaltigkeitsreporting.<\/p>\n\n<p class=\"wp-block-paragraph\">Es bedeutet auch, ein langfristiger Partner zu sein, der Betreiber dabei unterst\u00fctzt, zu wachsen, sich anzupassen und auf neue regulatorische und marktseitige Anforderungen zu reagieren.<\/p>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-personal-perspective-nbsp\"><p><strong>Pers\u00f6nliche Perspektive<\/strong><\/p><\/h2>\n\n<h3 class=\"wp-block-heading\" id=\"h-what-excites-you-most-about-this-next-chapter-for-orbisk-nbsp\"><p><strong>Was begeistert Sie pers\u00f6nlich an diesem n\u00e4chsten Kapitel f\u00fcr Orbisk?<\/strong><\/p><\/h3>\n\n<p class=\"wp-block-paragraph\">Mich begeistert vor allem das Ausma\u00df der Wirkung, die wir nun erschlie\u00dfen k\u00f6nnen. Orbisk arbeitet bereits mit globalen Hospitality- und Foodservice-Marken, die in mehreren Regionen wie etwa dem asiatisch-pazifischen Raum aktiv sind. Unsere Pr\u00e4senz dort weiter auszubauen, ist der logische n\u00e4chste Schritt.<\/p>\n\n<p class=\"wp-block-paragraph\">So k\u00f6nnen wir unsere Wirkung vergr\u00f6\u00dfern und noch mehr Mehrwert f\u00fcr Kunden schaffen, die weltweit einen Standard, einen Partner und verl\u00e4ssliche Ergebnisse erwarten.&#13;\n&#13;\nWir sind bereit f\u00fcr diese Phase. Im vergangenen Jahr haben wir von der Produktreife \u00fcber betriebliche Prozesse bis hin zur regionalen Expertise die Grundlagen f\u00fcr die globale Skalierung gelegt. Die Nachfrage ist offensichtlich und Orbisk ist daf\u00fcr gebaut, sie zu bedienen. Wir expandieren mit Zuversicht, weil wir wissen, dass unsere Technologie unabh\u00e4ngig von K\u00fcche, Format oder Region messbare Ergebnisse liefert.<\/p>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-a-final-message-nbsp\"><p><strong>Eine abschlie\u00dfende Botschaft<\/strong><\/p><\/h2>\n\n<h3 class=\"wp-block-heading\" id=\"h-if-you-could-send-one-message-to-food-service-operators-in-apac-what-would-it-be-nbsp\"><p><strong>Welche Botschaft m\u00f6chten Sie den Foodservice-Betreibern in APAC mitgeben?<\/strong><\/p><\/h3>\n\n<p class=\"wp-block-paragraph\">Lebensmittelabf\u00e4lle sind kein unvermeidbarer Kostenfaktor. Sie geh\u00f6ren zu den klarsten und schnellsten Hebeln, um Margen zu verbessern, Nachhaltigkeitsleistungen zu st\u00e4rken und Betriebe zukunftssicher aufzustellen.<\/p>\n\n<p class=\"wp-block-paragraph\">Die K\u00fcchen, die morgen f\u00fchrend sind, handeln schon heute. Mit den richtigen Daten und dem richtigen Partner werden Lebensmittelabf\u00e4lle sichtbar, steuerbar und messbar, wodurch schnell positive Ergebnisse folgen. Zero-Waste ist keine ferne Vision. Es ist der neue Standard. Und er beginnt jetzt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00dcber die Zero-Waste-Mission, globale Ambitionen und warum der asiatisch-pazifische Raum als N\u00e4chstes folgt Orbisks Vision und Dynamik Orbisk ist in den letzten Jahren stark gewachsen. Wie w\u00fcrden Sie heute den Fokus des Unternehmens beschreiben? Orbisk verfolgt ein klares Ziel: Lebensmittelabf\u00e4lle zu eliminieren und durch unsere weltweite F\u00fchrungsrolle im Bereich Food-Waste-Intelligence ein klimaneutrales Lebensmittelsystem zu erm\u00f6glichen. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":25547268,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[74],"tags":[],"dipi_cpt_category":[],"class_list":["post-25547356","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lebensmittel-fakten-und-zahlen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Q&amp;A mit Anastasia Dellis, Gesch\u00e4ftsf\u00fchrerin von Orbisk | Orbisk Blog<\/title>\n<meta name=\"description\" content=\"Q&amp;A mit Orbisk-Gesch\u00e4ftsf\u00fchrerin Anastasia Dellis \u00fcber die Reduzierung von Lebensmittelabf\u00e4llen, die globale Expansion und warum der asiatisch-pazifische Raum die n\u00e4chste Wachstumsregion f\u00fcr Zero-Waste-K\u00fcchen ist.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orbisk.com\/de\/blog\/qa-mit-anastasia-dellis-geschaeftsfuehrerin-von-orbisk\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Q&amp;A mit Anastasia Dellis, Gesch\u00e4ftsf\u00fchrerin von Orbisk | Orbisk Blog\" \/>\n<meta property=\"og:description\" content=\"Q&amp;A mit Orbisk-Gesch\u00e4ftsf\u00fchrerin Anastasia Dellis \u00fcber die Reduzierung von Lebensmittelabf\u00e4llen, die globale Expansion und warum der asiatisch-pazifische Raum die n\u00e4chste Wachstumsregion f\u00fcr Zero-Waste-K\u00fcchen ist.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orbisk.com\/de\/blog\/qa-mit-anastasia-dellis-geschaeftsfuehrerin-von-orbisk\/\" \/>\n<meta property=\"og:site_name\" content=\"Orbisk\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Orbiskzerofoodwaste\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-12T16:57:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-25T08:17:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/orbisk.com\/wp-content\/uploads\/2026\/01\/QA-blog-meta-1024x683.jpg\" \/>\n<meta name=\"author\" content=\"Jeroen Feron\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Q&amp;A mit Anastasia Dellis, Gesch\u00e4ftsf\u00fchrerin von Orbisk\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jeroen Feron\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/orbisk.com\\\/de\\\/blog\\\/qa-mit-anastasia-dellis-geschaeftsfuehrerin-von-orbisk\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orbisk.com\\\/de\\\/blog\\\/qa-mit-anastasia-dellis-geschaeftsfuehrerin-von-orbisk\\\/\"},\"author\":{\"name\":\"Jeroen Feron\",\"@id\":\"https:\\\/\\\/orbisk.com\\\/de\\\/#\\\/schema\\\/person\\\/a3e5bf2cbeb4172dab6adb9dfaab948d\"},\"headline\":\"Q&#038;A mit Anastasia Dellis, Gesch\u00e4ftsf\u00fchrerin von Orbisk\",\"datePublished\":\"2026-01-12T16:57:35+00:00\",\"dateModified\":\"2026-02-25T08:17:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/orbisk.com\\\/de\\\/blog\\\/qa-mit-anastasia-dellis-geschaeftsfuehrerin-von-orbisk\\\/\"},\"wordCount\":956,\"publisher\":{\"@id\":\"https:\\\/\\\/orbisk.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/orbisk.com\\\/de\\\/blog\\\/qa-mit-anastasia-dellis-geschaeftsfuehrerin-von-orbisk\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orbisk.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/QA-blog-meta-scaled.jpg\",\"articleSection\":[\"Lebensmittel Fakten &amp; Zahlen\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/orbisk.com\\\/de\\\/blog\\\/qa-mit-anastasia-dellis-geschaeftsfuehrerin-von-orbisk\\\/\",\"url\":\"https:\\\/\\\/orbisk.com\\\/de\\\/blog\\\/qa-mit-anastasia-dellis-geschaeftsfuehrerin-von-orbisk\\\/\",\"name\":\"Q&A mit Anastasia Dellis, Gesch\u00e4ftsf\u00fchrerin von Orbisk | Orbisk Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orbisk.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/orbisk.com\\\/de\\\/blog\\\/qa-mit-anastasia-dellis-geschaeftsfuehrerin-von-orbisk\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/orbisk.com\\\/de\\\/blog\\\/qa-mit-anastasia-dellis-geschaeftsfuehrerin-von-orbisk\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orbisk.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/QA-blog-meta-scaled.jpg\",\"datePublished\":\"2026-01-12T16:57:35+00:00\",\"dateModified\":\"2026-02-25T08:17:03+00:00\",\"description\":\"Q&A mit Orbisk-Gesch\u00e4ftsf\u00fchrerin Anastasia Dellis \u00fcber die Reduzierung von Lebensmittelabf\u00e4llen, die globale Expansion und warum der asiatisch-pazifische Raum die n\u00e4chste Wachstumsregion f\u00fcr Zero-Waste-K\u00fcchen ist.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/orbisk.com\\\/de\\\/blog\\\/qa-mit-anastasia-dellis-geschaeftsfuehrerin-von-orbisk\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/orbisk.com\\\/de\\\/blog\\\/qa-mit-anastasia-dellis-geschaeftsfuehrerin-von-orbisk\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/orbisk.com\\\/de\\\/blog\\\/qa-mit-anastasia-dellis-geschaeftsfuehrerin-von-orbisk\\\/#primaryimage\",\"url\":\"https:\\\/\\\/orbisk.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/QA-blog-meta-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/orbisk.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/QA-blog-meta-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/orbisk.com\\\/de\\\/blog\\\/qa-mit-anastasia-dellis-geschaeftsfuehrerin-von-orbisk\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/orbisk.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lebensmittel Fakten &amp; Zahlen\",\"item\":\"https:\\\/\\\/orbisk.com\\\/de\\\/blog\\\/category\\\/lebensmittel-fakten-und-zahlen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Q&#038;A mit Anastasia Dellis, Gesch\u00e4ftsf\u00fchrerin von Orbisk\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/orbisk.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/orbisk.com\\\/de\\\/\",\"name\":\"Orbisk - Zero Food Waste\",\"description\":\"Zero Food Waste\",\"publisher\":{\"@id\":\"https:\\\/\\\/orbisk.com\\\/de\\\/#organization\"},\"alternateName\":\"Orbisk\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/orbisk.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/orbisk.com\\\/de\\\/#organization\",\"name\":\"Orbisk\",\"url\":\"https:\\\/\\\/orbisk.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/orbisk.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/orbisk.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Orbisk-logo.png\",\"contentUrl\":\"https:\\\/\\\/orbisk.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Orbisk-logo.png\",\"width\":500,\"height\":385,\"caption\":\"Orbisk\"},\"image\":{\"@id\":\"https:\\\/\\\/orbisk.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Orbiskzerofoodwaste\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/18624102\\\/\",\"https:\\\/\\\/www.instagram.com\\\/orbisk\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/orbisk.com\\\/de\\\/#\\\/schema\\\/person\\\/a3e5bf2cbeb4172dab6adb9dfaab948d\",\"name\":\"Jeroen Feron\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/55c3a454a4679fb0aefb351bb8903415045a3360c1217a0bf1893d787bdcf00d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/55c3a454a4679fb0aefb351bb8903415045a3360c1217a0bf1893d787bdcf00d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/55c3a454a4679fb0aefb351bb8903415045a3360c1217a0bf1893d787bdcf00d?s=96&d=mm&r=g\",\"caption\":\"Jeroen Feron\"},\"sameAs\":[\"https:\\\/\\\/orbisk.com\"],\"url\":\"https:\\\/\\\/orbisk.com\\\/de\\\/blog\\\/author\\\/orbiskdev\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Q&A mit Anastasia Dellis, Gesch\u00e4ftsf\u00fchrerin von Orbisk | Orbisk Blog","description":"Q&A mit Orbisk-Gesch\u00e4ftsf\u00fchrerin Anastasia Dellis \u00fcber die Reduzierung von Lebensmittelabf\u00e4llen, die globale Expansion und warum der asiatisch-pazifische Raum die n\u00e4chste Wachstumsregion f\u00fcr Zero-Waste-K\u00fcchen ist.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orbisk.com\/de\/blog\/qa-mit-anastasia-dellis-geschaeftsfuehrerin-von-orbisk\/","og_locale":"de_DE","og_type":"article","og_title":"Q&A mit Anastasia Dellis, Gesch\u00e4ftsf\u00fchrerin von Orbisk | Orbisk Blog","og_description":"Q&A mit Orbisk-Gesch\u00e4ftsf\u00fchrerin Anastasia Dellis \u00fcber die Reduzierung von Lebensmittelabf\u00e4llen, die globale Expansion und warum der asiatisch-pazifische Raum die n\u00e4chste Wachstumsregion f\u00fcr Zero-Waste-K\u00fcchen ist.","og_url":"https:\/\/orbisk.com\/de\/blog\/qa-mit-anastasia-dellis-geschaeftsfuehrerin-von-orbisk\/","og_site_name":"Orbisk","article_publisher":"https:\/\/www.facebook.com\/Orbiskzerofoodwaste\/","article_published_time":"2026-01-12T16:57:35+00:00","article_modified_time":"2026-02-25T08:17:03+00:00","og_image":[{"url":"https:\/\/orbisk.com\/wp-content\/uploads\/2026\/01\/QA-blog-meta-1024x683.jpg","type":"","width":"","height":""}],"author":"Jeroen Feron","twitter_card":"summary_large_image","twitter_title":"Q&A mit Anastasia Dellis, Gesch\u00e4ftsf\u00fchrerin von Orbisk","twitter_misc":{"Verfasst von":"Jeroen Feron","Gesch\u00e4tzte Lesezeit":"5 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/orbisk.com\/de\/blog\/qa-mit-anastasia-dellis-geschaeftsfuehrerin-von-orbisk\/#article","isPartOf":{"@id":"https:\/\/orbisk.com\/de\/blog\/qa-mit-anastasia-dellis-geschaeftsfuehrerin-von-orbisk\/"},"author":{"name":"Jeroen Feron","@id":"https:\/\/orbisk.com\/de\/#\/schema\/person\/a3e5bf2cbeb4172dab6adb9dfaab948d"},"headline":"Q&#038;A mit Anastasia Dellis, Gesch\u00e4ftsf\u00fchrerin von Orbisk","datePublished":"2026-01-12T16:57:35+00:00","dateModified":"2026-02-25T08:17:03+00:00","mainEntityOfPage":{"@id":"https:\/\/orbisk.com\/de\/blog\/qa-mit-anastasia-dellis-geschaeftsfuehrerin-von-orbisk\/"},"wordCount":956,"publisher":{"@id":"https:\/\/orbisk.com\/de\/#organization"},"image":{"@id":"https:\/\/orbisk.com\/de\/blog\/qa-mit-anastasia-dellis-geschaeftsfuehrerin-von-orbisk\/#primaryimage"},"thumbnailUrl":"https:\/\/orbisk.com\/wp-content\/uploads\/2026\/01\/QA-blog-meta-scaled.jpg","articleSection":["Lebensmittel Fakten &amp; Zahlen"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/orbisk.com\/de\/blog\/qa-mit-anastasia-dellis-geschaeftsfuehrerin-von-orbisk\/","url":"https:\/\/orbisk.com\/de\/blog\/qa-mit-anastasia-dellis-geschaeftsfuehrerin-von-orbisk\/","name":"Q&A mit Anastasia Dellis, Gesch\u00e4ftsf\u00fchrerin von Orbisk | Orbisk Blog","isPartOf":{"@id":"https:\/\/orbisk.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/orbisk.com\/de\/blog\/qa-mit-anastasia-dellis-geschaeftsfuehrerin-von-orbisk\/#primaryimage"},"image":{"@id":"https:\/\/orbisk.com\/de\/blog\/qa-mit-anastasia-dellis-geschaeftsfuehrerin-von-orbisk\/#primaryimage"},"thumbnailUrl":"https:\/\/orbisk.com\/wp-content\/uploads\/2026\/01\/QA-blog-meta-scaled.jpg","datePublished":"2026-01-12T16:57:35+00:00","dateModified":"2026-02-25T08:17:03+00:00","description":"Q&A mit Orbisk-Gesch\u00e4ftsf\u00fchrerin Anastasia Dellis \u00fcber die Reduzierung von Lebensmittelabf\u00e4llen, die globale Expansion und warum der asiatisch-pazifische Raum die n\u00e4chste Wachstumsregion f\u00fcr Zero-Waste-K\u00fcchen ist.","breadcrumb":{"@id":"https:\/\/orbisk.com\/de\/blog\/qa-mit-anastasia-dellis-geschaeftsfuehrerin-von-orbisk\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orbisk.com\/de\/blog\/qa-mit-anastasia-dellis-geschaeftsfuehrerin-von-orbisk\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/orbisk.com\/de\/blog\/qa-mit-anastasia-dellis-geschaeftsfuehrerin-von-orbisk\/#primaryimage","url":"https:\/\/orbisk.com\/wp-content\/uploads\/2026\/01\/QA-blog-meta-scaled.jpg","contentUrl":"https:\/\/orbisk.com\/wp-content\/uploads\/2026\/01\/QA-blog-meta-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/orbisk.com\/de\/blog\/qa-mit-anastasia-dellis-geschaeftsfuehrerin-von-orbisk\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orbisk.com\/de\/"},{"@type":"ListItem","position":2,"name":"Lebensmittel Fakten &amp; Zahlen","item":"https:\/\/orbisk.com\/de\/blog\/category\/lebensmittel-fakten-und-zahlen\/"},{"@type":"ListItem","position":3,"name":"Q&#038;A mit Anastasia Dellis, Gesch\u00e4ftsf\u00fchrerin von Orbisk"}]},{"@type":"WebSite","@id":"https:\/\/orbisk.com\/de\/#website","url":"https:\/\/orbisk.com\/de\/","name":"Orbisk - Zero Food Waste","description":"Zero Food Waste","publisher":{"@id":"https:\/\/orbisk.com\/de\/#organization"},"alternateName":"Orbisk","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orbisk.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/orbisk.com\/de\/#organization","name":"Orbisk","url":"https:\/\/orbisk.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/orbisk.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/orbisk.com\/wp-content\/uploads\/2023\/02\/Orbisk-logo.png","contentUrl":"https:\/\/orbisk.com\/wp-content\/uploads\/2023\/02\/Orbisk-logo.png","width":500,"height":385,"caption":"Orbisk"},"image":{"@id":"https:\/\/orbisk.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Orbiskzerofoodwaste\/","https:\/\/www.linkedin.com\/company\/18624102\/","https:\/\/www.instagram.com\/orbisk\/"]},{"@type":"Person","@id":"https:\/\/orbisk.com\/de\/#\/schema\/person\/a3e5bf2cbeb4172dab6adb9dfaab948d","name":"Jeroen Feron","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/55c3a454a4679fb0aefb351bb8903415045a3360c1217a0bf1893d787bdcf00d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/55c3a454a4679fb0aefb351bb8903415045a3360c1217a0bf1893d787bdcf00d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55c3a454a4679fb0aefb351bb8903415045a3360c1217a0bf1893d787bdcf00d?s=96&d=mm&r=g","caption":"Jeroen Feron"},"sameAs":["https:\/\/orbisk.com"],"url":"https:\/\/orbisk.com\/de\/blog\/author\/orbiskdev\/"}]}},"modified_by":null,"_links":{"self":[{"href":"https:\/\/orbisk.com\/de\/wp-json\/wp\/v2\/posts\/25547356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orbisk.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/orbisk.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/orbisk.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/orbisk.com\/de\/wp-json\/wp\/v2\/comments?post=25547356"}],"version-history":[{"count":0,"href":"https:\/\/orbisk.com\/de\/wp-json\/wp\/v2\/posts\/25547356\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orbisk.com\/de\/wp-json\/wp\/v2\/media\/25547268"}],"wp:attachment":[{"href":"https:\/\/orbisk.com\/de\/wp-json\/wp\/v2\/media?parent=25547356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/orbisk.com\/de\/wp-json\/wp\/v2\/categories?post=25547356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/orbisk.com\/de\/wp-json\/wp\/v2\/tags?post=25547356"},{"taxonomy":"dipi_cpt_category","embeddable":true,"href":"https:\/\/orbisk.com\/de\/wp-json\/wp\/v2\/dipi_cpt_category?post=25547356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}