{"id":25547357,"date":"2026-01-12T16:57:35","date_gmt":"2026-01-12T16:57:35","guid":{"rendered":"https:\/\/orbisk.com\/blog\/entretien-avec-anastasia-dellis-ceo-dorbisk\/"},"modified":"2026-02-25T08:33:26","modified_gmt":"2026-02-25T08:33:26","slug":"entretien-avec-anastasia-dellis-ceo-dorbisk","status":"publish","type":"post","link":"https:\/\/orbisk.com\/fr\/blog\/entretien-avec-anastasia-dellis-ceo-dorbisk\/","title":{"rendered":"Entretien avec Anastasia Dellis, CEO d\u2019Orbisk"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\" id=\"h-on-the-zero-waste-mission-global-ambition-and-why-asia-pacific-is-next\">Mission z\u00e9ro gaspillage, expansion internationale et avenir en Asie-Pacifique<\/h1>\n\n<h2 class=\"wp-block-heading\" id=\"h-orbisk-s-vision-amp-momentum\"><p><strong>La vision et la dynamique d\u2019Orbisk<\/strong><\/p><\/h2>\n\n<h3 class=\"wp-block-heading\" id=\"h-orbisk-has-grown-rapidly-in-recent-years-how-do-you-describe-the-company-s-focus-today\"><p><strong>Orbisk a connu une croissance rapide ces derni\u00e8res ann\u00e9es. Comment d\u00e9cririez-vous aujourd\u2019hui l\u2019orientation de l\u2019entreprise ?<\/strong><\/p><\/h3>\n\n<p class=\"wp-block-paragraph\">Orbisk se concentre sur un objectif clair : \u00e9liminer le gaspillage alimentaire et contribuer \u00e0 un syst\u00e8me alimentaire neutre en carbone en devenant le leader mondial de l\u2019intelligence du gaspillage alimentaire.<\/p>\n\n<p class=\"wp-block-paragraph\">Ces derni\u00e8res ann\u00e9es, nous avons prouv\u00e9 que la r\u00e9duction du gaspillage alimentaire n\u2019est pas seulement un enjeu de durabilit\u00e9, mais aussi un v\u00e9ritable levier de performance. Lorsque les cuisines mesurent correctement leur gaspillage, elles r\u00e9duisent leurs co\u00fbts, gagnent en efficacit\u00e9 et prennent de meilleures d\u00e9cisions au quotidien.<\/p>\n\n<p class=\"wp-block-paragraph\">Aujourd\u2019hui, notre priorit\u00e9 est de d\u00e9ployer cet impact \u00e0 plus grande \u00e9chelle : accompagner davantage d\u2019op\u00e9rateurs, dans davantage de r\u00e9gions, avec une technologie capable de s\u2019adapter \u00e0 diff\u00e9rentes cuisines et r\u00e9alit\u00e9s op\u00e9rationnelles.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-what-does-global-leadership-mean-to-you-in-practice\"><p><strong>Selon vous, que signifie concr\u00e8tement le \u00ab leadership mondial \u00bb ?<\/strong><\/p><\/h3>\n\n<p class=\"wp-block-paragraph\">Le leadership mondial, c\u2019est \u00eatre pertinent partout o\u00f9 l\u2019on op\u00e8re. Pour Orbisk, cela implique d\u2019allier une ex\u00e9cution locale solide \u00e0 une plateforme coh\u00e9rente et pilot\u00e9e par les donn\u00e9es, sur laquelle les clients peuvent compter d\u2019une r\u00e9gion \u00e0 l\u2019autre.<\/p>\n\n<p class=\"wp-block-paragraph\">Cela implique \u00e9galement de d\u00e9velopper une intelligence \u00e0 grande \u00e9chelle. Plus nous accompagnons de cuisines professionnelles, plus nos analyses s\u2019enrichissent, ce qui se traduit par un meilleur service pour l\u2019ensemble de nos clients.<\/p>\n\n<hr class=\"wp-block-separator aligncenter has-alpha-channel-opacity is-style-wide\"\/>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-why-asia-pacific-why-now-nbsp\"><p><strong>Pourquoi l\u2019Asie-Pacifique, et pourquoi maintenant ?<\/strong><\/p><\/h2>\n\n<h3 class=\"wp-block-heading\" id=\"h-why-is-asia-pacific-such-an-important-region-for-orbisk-s-next-phase-of-growth\"><p><strong>Pourquoi l\u2019Asie-Pacifique est-elle une r\u00e9gion cl\u00e9 pour la prochaine phase de croissance d\u2019Orbisk ?<\/strong><\/p><\/h3>\n\n<p class=\"wp-block-paragraph\">L\u2019Asie-Pacifique est la r\u00e9gion de la restauration \u00e0 la croissance la plus rapide au monde. Les op\u00e9rateurs se d\u00e9veloppent rapidement, tandis que les co\u00fbts alimentaires augmentent et que les exigences en mati\u00e8re de durabilit\u00e9 et de reporting se renforcent.<\/p>\n\n<p class=\"wp-block-paragraph\">Par ailleurs, l\u2019Asie-Pacifique repr\u00e9sente la plus grande part du gaspillage alimentaire mondial. Des gouvernements, notamment \u00e0 Singapour, mettent en place des exigences plus claires en mati\u00e8re de mesure et de r\u00e9duction des d\u00e9chets. Les op\u00e9rateurs recherchent activement des solutions pour anticiper ces \u00e9volutions.<\/p>\n\n<p class=\"wp-block-paragraph\">Pour Orbisk, c\u2019est une r\u00e9gion o\u00f9 l\u2019impact, la demande et la maturit\u00e9 du march\u00e9 se rejoignent.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-what-challenges-do-food-service-operators-in-apac-face-today\"><p><strong>Quels d\u00e9fis les groupes de restauration en Asie-Pacifique rencontrent-ils aujourd\u2019hui ?<\/strong><\/p><\/h3>\n\n<p class=\"wp-block-paragraph\">Beaucoup arbitrent entre croissance et pression sur les marges. G\u00e9rer \u00e0 grande \u00e9chelle des menus complexes et des cuisines diverses s\u2019accompagne d\u00e9sormais d\u2019une exigence : r\u00e9duire les co\u00fbts et rendre la performance de durabilit\u00e9 visible et mesurable.<\/p>\n\n<p class=\"wp-block-paragraph\">Sans donn\u00e9es claires, le gaspillage reste invisible \u2014 et ce qui est invisible est difficile \u00e0 piloter. C\u2019est l\u00e0 qu\u2019Orbisk intervient, en apportant clart\u00e9, structure et solutions concr\u00e8tes au niveau de la cuisine.<\/p>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-what-orbisk-brings-to-the-region-nbsp\"><p><strong>Ce que propose Orbisk \u00e0 la r\u00e9gion<\/strong><\/p><\/h2>\n\n<h3 class=\"wp-block-heading\" id=\"h-how-does-orbisk-support-operators-as-they-scale-in-apac\"><p><strong>Comment Orbisk accompagne-t-il les groupes de restauration dans leur d\u00e9veloppement en Asie-Pacifique ?<\/strong><\/p><\/h3>\n\n<p class=\"wp-block-paragraph\">Orbisk aide les groupes de restauration \u00e0 transformer les donn\u00e9es de gaspillage en d\u00e9cisions op\u00e9rationnelles quotidiennes. Notre plateforme fournit des analyses claires pour les \u00e9quipes en cuisine, des rapports exploitables pour la direction et des r\u00e9sultats mesurables \u00e0 l\u2019\u00e9chelle de plusieurs \u00e9tablissements.<\/p>\n\n<p class=\"wp-block-paragraph\">Il est important de souligner que la solution s\u2019adapte aux cuisines et aux modes de fonctionnement locaux. R\u00e9duire le gaspillage dans un h\u00f4tel \u00e0 Singapour ne se pr\u00e9sente pas de la m\u00eame mani\u00e8re qu\u2019en Europe ; c\u2019est pourquoi Orbisk reste continuellement \u00e0 l\u2019\u00e9coute des retours de ses clients afin de faire \u00e9voluer sa technologie en ad\u00e9quation avec les besoins op\u00e9rationnels r\u00e9els.&#13;\n<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-what-does-orbisk-s-expansion-mean-for-international-brands-operating-across-regions\"><p><strong>Qu\u2019implique l\u2019expansion d\u2019Orbisk pour les marques internationales pr\u00e9sentes dans plusieurs r\u00e9gions ?<\/strong><\/p><\/h3>\n\n<p class=\"wp-block-paragraph\">Pour les marques globales et r\u00e9gionales, Orbisk apporte de la coh\u00e9rence : une m\u00e9thode unique de mesure et de r\u00e9duction du gaspillage, soutenue par une plateforme globale, avec des analyses adapt\u00e9es aux r\u00e9alit\u00e9s locales.<\/p>\n\n<p class=\"wp-block-paragraph\">Cela permet aux op\u00e9rateurs de se comparer entre r\u00e9gions, de d\u00e9ployer plus efficacement les meilleures pratiques et d\u2019aligner les objectifs de durabilit\u00e9 et les performances financi\u00e8res \u2014 sans alourdir les processus op\u00e9rationnels.<\/p>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-looking-ahead-where-orbisk-is-going-next-nbsp\"><p><strong>Cap sur l\u2019avenir : les prochaines \u00e9tapes pour Orbisk<\/strong><\/p><\/h2>\n\n<h3 class=\"wp-block-heading\" id=\"h-how-do-you-see-orbisk-evolving-over-the-next-few-years\"><p><strong>Comment voyez-vous Orbisk \u00e9voluer dans les prochaines ann\u00e9es ?<\/strong><\/p><\/h3>\n\n<p class=\"wp-block-paragraph\">Orbisk passe du statut de leader europ\u00e9en en forte croissance \u00e0 celui de v\u00e9ritable plateforme de r\u00e9f\u00e9rence mondiale en mati\u00e8re d\u2019intelligence du gaspillage alimentaire.<\/p>\n\n<p class=\"wp-block-paragraph\">Cette \u00e9volution se traduit par une pr\u00e9sence r\u00e9gionale renforc\u00e9e, des partenariats strat\u00e9giques \u00e9largis et des investissements soutenus dans l\u2019intelligence artificielle, les donn\u00e9es et l\u2019innovation produit. Plus notre base de donn\u00e9es s\u2019\u00e9tend, plus la valeur g\u00e9n\u00e9r\u00e9e pour nos clients est importante.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-what-does-success-in-apac-look-like-for-orbisk\"><p><strong>Comment se d\u00e9finit le succ\u00e8s d\u2019Orbisk en Asie-Pacifique ?<\/strong><\/p><\/h3>\n\n<p class=\"wp-block-paragraph\">Le succ\u00e8s se mesure par des r\u00e9sultats concrets et mesurables pour nos clients : moins de gaspillage alimentaire, des co\u00fbts optimis\u00e9s et des rapports ESG plus fiables.<\/p>\n\n<p class=\"wp-block-paragraph\">C\u2019est \u00e9galement construire des partenariats durables, en accompagnant les op\u00e9rateurs \u00e0 chaque \u00e9tape de leur d\u00e9veloppement, face aux nouvelles r\u00e9glementations et aux \u00e9volutions constantes du march\u00e9.<\/p>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-personal-perspective-nbsp\"><p><strong>Perspective personnelle<\/strong><\/p><\/h2>\n\n<h3 class=\"wp-block-heading\" id=\"h-what-excites-you-most-about-this-next-chapter-for-orbisk-nbsp\"><p><strong>Qu\u2019est-ce qui vous enthousiasme le plus dans ce nouveau chapitre pour Orbisk ?<\/strong><\/p><\/h3>\n\n<p class=\"wp-block-paragraph\">Ce qui m\u2019enthousiasme le plus, c\u2019est l\u2019ampleur de l\u2019impact que nous nous appr\u00eatons \u00e0 d\u00e9ployer. Orbisk collabore d\u00e9j\u00e0 avec des leaders mondiaux de l\u2019h\u00f4tellerie et de la restauration pr\u00e9sents dans plusieurs r\u00e9gions, y compris en Asie-Pacifique. Renforcer notre pr\u00e9sence dans cette zone constitue une \u00e9tape naturelle. Cela nous permet d\u2019\u00e9largir notre impact et d\u2019apporter encore plus de valeur aux clients qui recherchent un standard unique, un partenaire unique et des r\u00e9sultats \u00e9prouv\u00e9s dans l\u2019ensemble de leurs op\u00e9rations.<\/p>\n\n<p class=\"wp-block-paragraph\">Nous sommes pr\u00eats pour cette phase. Au cours de l\u2019ann\u00e9e \u00e9coul\u00e9e, nous avons pos\u00e9 les bases d\u2019un d\u00e9ploiement mondial, qu\u2019il s\u2019agisse de la maturit\u00e9 du produit, de la pr\u00e9paration op\u00e9rationnelle ou de l\u2019expertise r\u00e9gionale. La demande est bien r\u00e9elle, et Orbisk est structur\u00e9 pour y r\u00e9pondre. Nous poursuivons notre expansion avec confiance, car notre technologie d\u00e9montre des r\u00e9sultats mesurables, quel que soit la cuisine, le format ou la zone g\u00e9ographique.<\/p>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-a-final-message-nbsp\"><p><strong>Message de conclusion<\/strong><\/p><\/h2>\n\n<h3 class=\"wp-block-heading\" id=\"h-if-you-could-send-one-message-to-food-service-operators-in-apac-what-would-it-be-nbsp\"><p><strong>Si vous pouviez adresser un message aux groupes de restauration en Asie-Pacifique, quel serait-il ?<\/strong><\/p><\/h3>\n\n<p class=\"wp-block-paragraph\">Le gaspillage alimentaire n\u2019est pas un co\u00fbt in\u00e9vitable. Il repr\u00e9sente au contraire l\u2019un des leviers les plus puissants pour am\u00e9liorer la rentabilit\u00e9, renforcer l\u2019impact environnemental et s\u00e9curiser l\u2019avenir des op\u00e9rations.<\/p>\n\n<p class=\"wp-block-paragraph\">Les \u00e9tablissements qui feront la diff\u00e9rence demain sont ceux qui prennent des d\u00e9cisions d\u00e8s aujourd\u2019hui. Avec les bonnes donn\u00e9es et le bon partenaire, le gaspillage devient visible, ma\u00eetrisable et mesurable \u2014 et les r\u00e9sultats suivent rapidement. Le z\u00e9ro gaspillage n\u2019est pas une ambition lointaine. C\u2019est le nouveau standard, et il commence d\u00e8s maintenant.&#13;\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mission z\u00e9ro gaspillage, expansion internationale et avenir en Asie-Pacifique La vision et la dynamique d\u2019Orbisk Orbisk a connu une croissance rapide ces derni\u00e8res ann\u00e9es. Comment d\u00e9cririez-vous aujourd\u2019hui l\u2019orientation de l\u2019entreprise ? Orbisk se concentre sur un objectif clair : \u00e9liminer le gaspillage alimentaire et contribuer \u00e0 un syst\u00e8me alimentaire neutre en carbone en devenant le [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":25547267,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[73],"tags":[],"dipi_cpt_category":[],"class_list":["post-25547357","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-faits-et-chiffres-alimentaires"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Entretien avec Anastasia Dellis, CEO d\u2019Orbisk | Orbisk Blog<\/title>\n<meta name=\"description\" content=\"Entretien avec Anastasia Dellis, CEO d\u2019Orbisk, sur la lutte contre le gaspillage alimentaire, la croissance internationale et le r\u00f4le cl\u00e9 de l\u2019Asie-Pacifique dans l\u2019avenir des cuisines z\u00e9ro d\u00e9chet.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orbisk.com\/fr\/blog\/entretien-avec-anastasia-dellis-ceo-dorbisk\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entretien avec Anastasia Dellis, CEO d\u2019Orbisk | Orbisk Blog\" \/>\n<meta property=\"og:description\" content=\"Entretien avec Anastasia Dellis, CEO d\u2019Orbisk, sur la lutte contre le gaspillage alimentaire, la croissance internationale et le r\u00f4le cl\u00e9 de l\u2019Asie-Pacifique dans l\u2019avenir des cuisines z\u00e9ro d\u00e9chet.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orbisk.com\/fr\/blog\/entretien-avec-anastasia-dellis-ceo-dorbisk\/\" \/>\n<meta property=\"og:site_name\" content=\"Orbisk\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Orbiskzerofoodwaste\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-12T16:57:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-25T08:33:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/orbisk.com\/wp-content\/uploads\/2026\/01\/QA-blog-meta-1024x683.jpg\" \/>\n<meta name=\"author\" content=\"Jeroen Feron\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Entretien avec Anastasia Dellis, CEO d\u2019Orbisk\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jeroen Feron\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/orbisk.com\\\/fr\\\/blog\\\/entretien-avec-anastasia-dellis-ceo-dorbisk\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orbisk.com\\\/fr\\\/blog\\\/entretien-avec-anastasia-dellis-ceo-dorbisk\\\/\"},\"author\":{\"name\":\"Jeroen Feron\",\"@id\":\"https:\\\/\\\/orbisk.com\\\/fr\\\/#\\\/schema\\\/person\\\/a3e5bf2cbeb4172dab6adb9dfaab948d\"},\"headline\":\"Entretien avec Anastasia Dellis, CEO d\u2019Orbisk\",\"datePublished\":\"2026-01-12T16:57:35+00:00\",\"dateModified\":\"2026-02-25T08:33:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/orbisk.com\\\/fr\\\/blog\\\/entretien-avec-anastasia-dellis-ceo-dorbisk\\\/\"},\"wordCount\":1195,\"publisher\":{\"@id\":\"https:\\\/\\\/orbisk.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/orbisk.com\\\/fr\\\/blog\\\/entretien-avec-anastasia-dellis-ceo-dorbisk\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orbisk.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/QA-blog-meta-scaled.jpg\",\"articleSection\":[\"Faits et Chiffres Alimentaires\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/orbisk.com\\\/fr\\\/blog\\\/entretien-avec-anastasia-dellis-ceo-dorbisk\\\/\",\"url\":\"https:\\\/\\\/orbisk.com\\\/fr\\\/blog\\\/entretien-avec-anastasia-dellis-ceo-dorbisk\\\/\",\"name\":\"Entretien avec Anastasia Dellis, CEO d\u2019Orbisk | Orbisk Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orbisk.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/orbisk.com\\\/fr\\\/blog\\\/entretien-avec-anastasia-dellis-ceo-dorbisk\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/orbisk.com\\\/fr\\\/blog\\\/entretien-avec-anastasia-dellis-ceo-dorbisk\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orbisk.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/QA-blog-meta-scaled.jpg\",\"datePublished\":\"2026-01-12T16:57:35+00:00\",\"dateModified\":\"2026-02-25T08:33:26+00:00\",\"description\":\"Entretien avec Anastasia Dellis, CEO d\u2019Orbisk, sur la lutte contre le gaspillage alimentaire, la croissance internationale et le r\u00f4le cl\u00e9 de l\u2019Asie-Pacifique dans l\u2019avenir des cuisines z\u00e9ro d\u00e9chet.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/orbisk.com\\\/fr\\\/blog\\\/entretien-avec-anastasia-dellis-ceo-dorbisk\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/orbisk.com\\\/fr\\\/blog\\\/entretien-avec-anastasia-dellis-ceo-dorbisk\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/orbisk.com\\\/fr\\\/blog\\\/entretien-avec-anastasia-dellis-ceo-dorbisk\\\/#primaryimage\",\"url\":\"https:\\\/\\\/orbisk.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/QA-blog-meta-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/orbisk.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/QA-blog-meta-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/orbisk.com\\\/fr\\\/blog\\\/entretien-avec-anastasia-dellis-ceo-dorbisk\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/orbisk.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Faits et Chiffres Alimentaires\",\"item\":\"https:\\\/\\\/orbisk.com\\\/fr\\\/blog\\\/category\\\/faits-et-chiffres-alimentaires\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Entretien avec Anastasia Dellis, CEO d\u2019Orbisk\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/orbisk.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/orbisk.com\\\/fr\\\/\",\"name\":\"Orbisk - Zero Food Waste\",\"description\":\"Zero Food Waste\",\"publisher\":{\"@id\":\"https:\\\/\\\/orbisk.com\\\/fr\\\/#organization\"},\"alternateName\":\"Orbisk\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/orbisk.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/orbisk.com\\\/fr\\\/#organization\",\"name\":\"Orbisk\",\"url\":\"https:\\\/\\\/orbisk.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/orbisk.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/orbisk.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Orbisk-logo.png\",\"contentUrl\":\"https:\\\/\\\/orbisk.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Orbisk-logo.png\",\"width\":500,\"height\":385,\"caption\":\"Orbisk\"},\"image\":{\"@id\":\"https:\\\/\\\/orbisk.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Orbiskzerofoodwaste\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/18624102\\\/\",\"https:\\\/\\\/www.instagram.com\\\/orbisk\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/orbisk.com\\\/fr\\\/#\\\/schema\\\/person\\\/a3e5bf2cbeb4172dab6adb9dfaab948d\",\"name\":\"Jeroen Feron\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/55c3a454a4679fb0aefb351bb8903415045a3360c1217a0bf1893d787bdcf00d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/55c3a454a4679fb0aefb351bb8903415045a3360c1217a0bf1893d787bdcf00d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/55c3a454a4679fb0aefb351bb8903415045a3360c1217a0bf1893d787bdcf00d?s=96&d=mm&r=g\",\"caption\":\"Jeroen Feron\"},\"sameAs\":[\"https:\\\/\\\/orbisk.com\"],\"url\":\"https:\\\/\\\/orbisk.com\\\/fr\\\/blog\\\/author\\\/orbiskdev\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Entretien avec Anastasia Dellis, CEO d\u2019Orbisk | Orbisk Blog","description":"Entretien avec Anastasia Dellis, CEO d\u2019Orbisk, sur la lutte contre le gaspillage alimentaire, la croissance internationale et le r\u00f4le cl\u00e9 de l\u2019Asie-Pacifique dans l\u2019avenir des cuisines z\u00e9ro d\u00e9chet.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orbisk.com\/fr\/blog\/entretien-avec-anastasia-dellis-ceo-dorbisk\/","og_locale":"fr_FR","og_type":"article","og_title":"Entretien avec Anastasia Dellis, CEO d\u2019Orbisk | Orbisk Blog","og_description":"Entretien avec Anastasia Dellis, CEO d\u2019Orbisk, sur la lutte contre le gaspillage alimentaire, la croissance internationale et le r\u00f4le cl\u00e9 de l\u2019Asie-Pacifique dans l\u2019avenir des cuisines z\u00e9ro d\u00e9chet.","og_url":"https:\/\/orbisk.com\/fr\/blog\/entretien-avec-anastasia-dellis-ceo-dorbisk\/","og_site_name":"Orbisk","article_publisher":"https:\/\/www.facebook.com\/Orbiskzerofoodwaste\/","article_published_time":"2026-01-12T16:57:35+00:00","article_modified_time":"2026-02-25T08:33:26+00:00","og_image":[{"url":"https:\/\/orbisk.com\/wp-content\/uploads\/2026\/01\/QA-blog-meta-1024x683.jpg","type":"","width":"","height":""}],"author":"Jeroen Feron","twitter_card":"summary_large_image","twitter_title":"Entretien avec Anastasia Dellis, CEO d\u2019Orbisk","twitter_misc":{"\u00c9crit par":"Jeroen Feron","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/orbisk.com\/fr\/blog\/entretien-avec-anastasia-dellis-ceo-dorbisk\/#article","isPartOf":{"@id":"https:\/\/orbisk.com\/fr\/blog\/entretien-avec-anastasia-dellis-ceo-dorbisk\/"},"author":{"name":"Jeroen Feron","@id":"https:\/\/orbisk.com\/fr\/#\/schema\/person\/a3e5bf2cbeb4172dab6adb9dfaab948d"},"headline":"Entretien avec Anastasia Dellis, CEO d\u2019Orbisk","datePublished":"2026-01-12T16:57:35+00:00","dateModified":"2026-02-25T08:33:26+00:00","mainEntityOfPage":{"@id":"https:\/\/orbisk.com\/fr\/blog\/entretien-avec-anastasia-dellis-ceo-dorbisk\/"},"wordCount":1195,"publisher":{"@id":"https:\/\/orbisk.com\/fr\/#organization"},"image":{"@id":"https:\/\/orbisk.com\/fr\/blog\/entretien-avec-anastasia-dellis-ceo-dorbisk\/#primaryimage"},"thumbnailUrl":"https:\/\/orbisk.com\/wp-content\/uploads\/2026\/01\/QA-blog-meta-scaled.jpg","articleSection":["Faits et Chiffres Alimentaires"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/orbisk.com\/fr\/blog\/entretien-avec-anastasia-dellis-ceo-dorbisk\/","url":"https:\/\/orbisk.com\/fr\/blog\/entretien-avec-anastasia-dellis-ceo-dorbisk\/","name":"Entretien avec Anastasia Dellis, CEO d\u2019Orbisk | Orbisk Blog","isPartOf":{"@id":"https:\/\/orbisk.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/orbisk.com\/fr\/blog\/entretien-avec-anastasia-dellis-ceo-dorbisk\/#primaryimage"},"image":{"@id":"https:\/\/orbisk.com\/fr\/blog\/entretien-avec-anastasia-dellis-ceo-dorbisk\/#primaryimage"},"thumbnailUrl":"https:\/\/orbisk.com\/wp-content\/uploads\/2026\/01\/QA-blog-meta-scaled.jpg","datePublished":"2026-01-12T16:57:35+00:00","dateModified":"2026-02-25T08:33:26+00:00","description":"Entretien avec Anastasia Dellis, CEO d\u2019Orbisk, sur la lutte contre le gaspillage alimentaire, la croissance internationale et le r\u00f4le cl\u00e9 de l\u2019Asie-Pacifique dans l\u2019avenir des cuisines z\u00e9ro d\u00e9chet.","breadcrumb":{"@id":"https:\/\/orbisk.com\/fr\/blog\/entretien-avec-anastasia-dellis-ceo-dorbisk\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orbisk.com\/fr\/blog\/entretien-avec-anastasia-dellis-ceo-dorbisk\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/orbisk.com\/fr\/blog\/entretien-avec-anastasia-dellis-ceo-dorbisk\/#primaryimage","url":"https:\/\/orbisk.com\/wp-content\/uploads\/2026\/01\/QA-blog-meta-scaled.jpg","contentUrl":"https:\/\/orbisk.com\/wp-content\/uploads\/2026\/01\/QA-blog-meta-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/orbisk.com\/fr\/blog\/entretien-avec-anastasia-dellis-ceo-dorbisk\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orbisk.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Faits et Chiffres Alimentaires","item":"https:\/\/orbisk.com\/fr\/blog\/category\/faits-et-chiffres-alimentaires\/"},{"@type":"ListItem","position":3,"name":"Entretien avec Anastasia Dellis, CEO d\u2019Orbisk"}]},{"@type":"WebSite","@id":"https:\/\/orbisk.com\/fr\/#website","url":"https:\/\/orbisk.com\/fr\/","name":"Orbisk - Zero Food Waste","description":"Zero Food Waste","publisher":{"@id":"https:\/\/orbisk.com\/fr\/#organization"},"alternateName":"Orbisk","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orbisk.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/orbisk.com\/fr\/#organization","name":"Orbisk","url":"https:\/\/orbisk.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/orbisk.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/orbisk.com\/wp-content\/uploads\/2023\/02\/Orbisk-logo.png","contentUrl":"https:\/\/orbisk.com\/wp-content\/uploads\/2023\/02\/Orbisk-logo.png","width":500,"height":385,"caption":"Orbisk"},"image":{"@id":"https:\/\/orbisk.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Orbiskzerofoodwaste\/","https:\/\/www.linkedin.com\/company\/18624102\/","https:\/\/www.instagram.com\/orbisk\/"]},{"@type":"Person","@id":"https:\/\/orbisk.com\/fr\/#\/schema\/person\/a3e5bf2cbeb4172dab6adb9dfaab948d","name":"Jeroen Feron","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/55c3a454a4679fb0aefb351bb8903415045a3360c1217a0bf1893d787bdcf00d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/55c3a454a4679fb0aefb351bb8903415045a3360c1217a0bf1893d787bdcf00d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55c3a454a4679fb0aefb351bb8903415045a3360c1217a0bf1893d787bdcf00d?s=96&d=mm&r=g","caption":"Jeroen Feron"},"sameAs":["https:\/\/orbisk.com"],"url":"https:\/\/orbisk.com\/fr\/blog\/author\/orbiskdev\/"}]}},"modified_by":null,"_links":{"self":[{"href":"https:\/\/orbisk.com\/fr\/wp-json\/wp\/v2\/posts\/25547357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orbisk.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/orbisk.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/orbisk.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/orbisk.com\/fr\/wp-json\/wp\/v2\/comments?post=25547357"}],"version-history":[{"count":0,"href":"https:\/\/orbisk.com\/fr\/wp-json\/wp\/v2\/posts\/25547357\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orbisk.com\/fr\/wp-json\/wp\/v2\/media\/25547267"}],"wp:attachment":[{"href":"https:\/\/orbisk.com\/fr\/wp-json\/wp\/v2\/media?parent=25547357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/orbisk.com\/fr\/wp-json\/wp\/v2\/categories?post=25547357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/orbisk.com\/fr\/wp-json\/wp\/v2\/tags?post=25547357"},{"taxonomy":"dipi_cpt_category","embeddable":true,"href":"https:\/\/orbisk.com\/fr\/wp-json\/wp\/v2\/dipi_cpt_category?post=25547357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}